{"id":108,"date":"2019-10-30T17:07:10","date_gmt":"2019-10-30T17:07:10","guid":{"rendered":"https:\/\/www.nachlass-berres.de\/?page_id=108"},"modified":"2022-04-12T10:32:57","modified_gmt":"2022-04-12T10:32:57","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/www.nachlass-berres.de\/index.php\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"108\" class=\"elementor elementor-108\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a182439 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5a182439\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-207bda73\" data-id=\"207bda73\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e7e4917 elementor-widget elementor-widget-text-editor\" data-id=\"3e7e4917\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<h2 class=\"wp-block-heading\">1. Datenschutz auf einen Blick<\/h2>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Allgemeine Hinweise<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Datenerfassung auf unserer Website<\/h4>\n<p><\/p>\n<p><\/p>\n<p><strong>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/strong><\/p>\n<p><\/p>\n<p><\/p>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Impressum dieser Website entnehmen.<\/p>\n<p><\/p>\n<p><\/p>\n<p><strong>Wie erfassen wir Ihre Daten?<\/strong><\/p>\n<p><\/p>\n<p><\/p>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Andere Daten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n<p><\/p>\n<p><\/p>\n<p><strong>Wof\u00fcr nutzen wir Ihre Daten?<\/strong><\/p>\n<p><\/p>\n<p><\/p>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<p><\/p>\n<p><\/p>\n<p><strong>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/strong><\/p>\n<p><\/p>\n<p><\/p>\n<p>Sie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p><\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">2. Allgemeine Hinweise und Pflichtinformationen<\/h3>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Benennung der verantwortlichen Stelle f\u00fcr den Inhalt der Website<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p><\/p>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>Philipp M. Berres Nachlassverwaltungen<\/li>\n<li>Philipp Berres<\/li>\n<li>Salmstra\u00dfe 3 B<\/li>\n<li>54528 Salmtal<\/li>\n<\/ul>\n<p><\/p>\n<p><\/p>\n<p>Die verantwortliche Stelle entscheidet allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.B. Namen, Kontaktdaten oder \u00c4hnliches).<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Datenschutz<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Einige Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. F\u00fcr den Widerruf gen\u00fcgt eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Im Falle datenschutzrechtlicher Verst\u00f6\u00dfe steht dem Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Zust\u00e4ndige Aufsichtsbeh\u00f6rde in datenschutzrechtlichen Fragen ist der Landesdatenschutzbeauftragte des Bundeslandes, in dem sich der Sitz unseres Unternehmens befindet. Eine Liste der Datenschutzbeauftragten sowie deren Kontaktdaten k\u00f6nnen folgendem Link entnommen werden:&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\">https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html<\/a>.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Recht auf Daten\u00fcbertragbarkeit<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">SSL- bzw. TLS-Verschl\u00fcsselung<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL-bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201chttp:\/\/\u201d auf \u201chttps:\/\/\u201d wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Recht auf Auskunft, Berichtigung, Sperrung, L\u00f6schung<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Diesbez\u00fcglich und auch zu weiteren Fragen zum Thema personenbezogener Daten, k\u00f6nnen Sie sich jederzeit \u00fcber die im Impressum aufgef\u00fchrten Kontaktm\u00f6glichkeiten an uns wenden.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Widerspruch gegen Werbe-Mails<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Der Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<p><\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">3. Datenerfassung auf unserer Website<\/h3>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Server-Log-Dateien<\/h4>\n<p><\/p>\n<p><\/p>\n<p>In Server-Log-Dateien erhebt und speichert der Provider der Website automatisch Informationen, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<p><\/p>\n<p><\/p>\n<ul class=\"wp-block-list\">\n<li>Browsertyp und Browserversion<\/li>\n<li>verwendetes Betriebssystem<\/li>\n<li>Referrer URL<\/li>\n<li>Hostname des zugreifenden Rechners<\/li>\n<li>Uhrzeit der Serveranfrage<\/li>\n<li>IP-Adresse<\/li>\n<\/ul>\n<p><\/p>\n<p><\/p>\n<p>Eine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Grundlage der Datenverarbeitung bildet Art. 6 Abs. 1 lit. f DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet. Der Webseitenbetreiber hat ein berechtigtes Interesse an der technisch fehlerfreien Darstellung und der Optimierung seiner Webseite \u2013 hierzu m\u00fcssen die Server-Log-Files erfasst werden.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Kontaktformular<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Eine Weitergabe dieser Daten findet, ohne ihre Einwilligung, nicht statt.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die Verarbeitung der in das Kontaktformular eingegebenen Daten erfolgt somit ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen diese Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt.                                                                                            Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Verarbeiten von Daten (Kunden- und Vertragsdaten)<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Wir erheben, verarbeiten und nutzen personenbezogene Daten nur, soweit sie f\u00fcr die Begr\u00fcndung, inhaltliche Ausgestaltung oder \u00c4nderung des Rechtsverh\u00e4ltnisses erforderlich sind (Bestandsdaten). Dies erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet. Personenbezogene Daten \u00fcber die Inanspruchnahme unserer Internetseiten (Nutzungsdaten) erheben, verarbeiten und nutzen wir nur, soweit dies erforderlich ist, um dem Nutzer die Inanspruchnahme des Dienstes zu erm\u00f6glichen oder abzurechnen.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die erhobenen Kundendaten werden nach Abschluss des Auftrags oder Beendigung der Gesch\u00e4ftsbeziehung gel\u00f6scht. Gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n<p><\/p>\n<p><\/p>\n<h3 class=\"wp-block-heading\">4. Plugins und Tools<\/h3>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Cookies<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Unsere Website verwendet Cookies. Das sind kleine Textdateien, die Ihr Webbrowser auf Ihrem Endger\u00e4t speichert. Cookies helfen uns dabei, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Einige Cookies sind \u201cSession-Cookies.\u201d Solche Cookies werden nach Ende Ihrer Browser-Sitzung von selbst gel\u00f6scht. Hingegen bleiben andere Cookies auf Ihrem Endger\u00e4t bestehen, bis Sie diese selbst l\u00f6schen. Solche Cookies helfen uns, Sie bei R\u00fcckkehr auf unserer Website wiederzuerkennen.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Mit einem modernen Webbrowser k\u00f6nnen Sie das Setzen von Cookies \u00fcberwachen, einschr\u00e4nken oder unterbinden. Viele Webbrowser lassen sich so konfigurieren, dass Cookies mit dem Schlie\u00dfen des Programms von selbst gel\u00f6scht werden. Die Deaktivierung von Cookies kann eine eingeschr\u00e4nkte Funktionalit\u00e4t unserer Website zur Folge haben.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Das Setzen von Cookies, die zur Aus\u00fcbung elektronischer Kommunikationsvorg\u00e4nge oder der Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.B. Warenkorb) notwendig sind, erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Als Betreiber dieser Website haben wir ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und reibungslosen Bereitstellung unserer Dienste. Sofern die Setzung anderer Cookies (z.B. f\u00fcr Analyse-Funktionen) erfolgt, werden diese in dieser Datenschutzerkl\u00e4rung separat behandelt.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Google Web Fonts<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Web Fonts, die von Google bereitgestellt werden. Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Google aufnehmen. Hierdurch erlangt Google Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse unsere Website aufgerufen wurde. Die Nutzung von Google Web Fonts erfolgt im Interesse einer einheitlichen und ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Wenn Ihr Browser Web Fonts nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem Computer genutzt.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Weitere Informationen zu Google Web Fonts finden Sie unter&nbsp;<a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/developers.google.com\/fonts\/faq<\/a>&nbsp;und in der Datenschutzerkl\u00e4rung von Google:&nbsp;<a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.com\/policies\/privacy\/<\/a>.<\/p>\n<p><\/p>\n<p><\/p>\n<h4 class=\"wp-block-heading\">Google Maps<\/h4>\n<p><\/p>\n<p><\/p>\n<p>Diese Seite nutzt \u00fcber eine API den Kartendienst Google Maps. Anbieter ist die Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP Adresse zu speichern. Diese Informationen werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Der Anbieter dieser Seite hat keinen Einfluss auf diese Daten\u00fcbertragung.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit der von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p><\/p>\n<p><\/p>\n<p>Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Google:&nbsp;<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/<\/a>.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer Website [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-108","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/pages\/108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/comments?post=108"}],"version-history":[{"count":19,"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/pages\/108\/revisions"}],"predecessor-version":[{"id":618,"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/pages\/108\/revisions\/618"}],"wp:attachment":[{"href":"https:\/\/www.nachlass-berres.de\/index.php\/wp-json\/wp\/v2\/media?parent=108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}